{"id":8,"count":174,"description":"","link":"https:\/\/genrontrucktrailer.com\/fr\/category\/news\/","name":"Actualit\u00e9s","slug":"nouvelles","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News Archived - Genron International Trade<\/title>\n<meta name=\"description\" content=\"News - Genron International Trade\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/genrontrucktrailer.com\/fr\/37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d037225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5ba37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d037225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5b037225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d137225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac58237225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d037225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5b537225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d037225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5b337225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d037225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5be37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d137225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac58037225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d037225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5b837225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d137225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac58f\/37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d037225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5bd37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d037225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5be37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d037225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5b237225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d037225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5be37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d137225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac58137225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d137225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac58237225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5d037225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5b8\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News Archived - Genron International Trade\" \/>\n<meta property=\"og:description\" content=\"News - Genron International Trade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/genrontrucktrailer.com\/fr\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}ba{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b5{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b3{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}80{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}8f\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}bd{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b2{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}81{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8\/\" \/>\n<meta property=\"og:site_name\" content=\"Genron International Trade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}ba{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b5{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b3{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}80{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}8f\\\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}bd{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b2{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}81{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8\\\/\",\"url\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}ba{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b5{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b3{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}80{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}8f\\\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}bd{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b2{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}81{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8\\\/\",\"name\":\"News Archived - Genron International Trade\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/#website\"},\"description\":\"News - Genron International Trade\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}ba{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b5{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b3{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}80{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}8f\\\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}bd{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b2{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}81{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}ba{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b5{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b3{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}80{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}8f\\\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}bd{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b2{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}81{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/\",\"name\":\"Genron International Trade\",\"description\":\"Genron International Trade specialises in providing all types of semi-trailers for manufacture as well as sale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/#organization\",\"name\":\"Genron International Trade\",\"url\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/genrontrucktrailer.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo201911111655359700994.webp\",\"contentUrl\":\"https:\\\/\\\/genrontrucktrailer.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo201911111655359700994.webp\",\"width\":160,\"height\":90,\"caption\":\"Genron International Trade\"},\"image\":{\"@id\":\"https:\\\/\\\/genrontrucktrailer.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News Archived - Genron International Trade","description":"Actualit\u00e9s - Genron International Trade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/genrontrucktrailer.com\/fr\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}ba{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b5{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b3{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}80{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}8f\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}bd{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b2{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}81{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8\/","og_locale":"fr_FR","og_type":"article","og_title":"News Archived - Genron International Trade","og_description":"News - Genron International Trade","og_url":"https:\/\/genrontrucktrailer.com\/fr\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}ba{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b5{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b3{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}80{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}8f\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}bd{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b2{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}81{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8\/","og_site_name":"Genron International Trade","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/genrontrucktrailer.com\/ru\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}ba{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b5{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b3{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}80{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}8f\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}bd{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b2{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}81{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8\/","url":"https:\/\/genrontrucktrailer.com\/ru\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}ba{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b5{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b3{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}80{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}8f\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}bd{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b2{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}81{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8\/","name":"Nouvelles archiv\u00e9es - Genron International Trade","isPartOf":{"@id":"https:\/\/genrontrucktrailer.com\/ru\/#website"},"description":"Actualit\u00e9s - Genron International Trade","breadcrumb":{"@id":"https:\/\/genrontrucktrailer.com\/ru\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}ba{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b5{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b3{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}80{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}8f\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}bd{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b2{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}81{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/genrontrucktrailer.com\/ru\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}ba{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b5{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b3{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}80{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}8f\/{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}bd{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b2{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}be{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}81{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d1{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}82{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}d0{37225ea3bd2eb7b104d90b5983741938b5fdddea3a4559fcf702d4fdcfeb0ac5}b8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/genrontrucktrailer.com\/ru\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/genrontrucktrailer.com\/ru\/#website","url":"https:\/\/genrontrucktrailer.com\/ru\/","name":"Genron International Trade","description":"Genron International Trade est sp\u00e9cialis\u00e9e dans la fourniture de tous types de semi-remorques, tant pour la fabrication que pour la vente.","publisher":{"@id":"https:\/\/genrontrucktrailer.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/genrontrucktrailer.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/genrontrucktrailer.com\/ru\/#organization","name":"Genron International Trade","url":"https:\/\/genrontrucktrailer.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/genrontrucktrailer.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/genrontrucktrailer.com\/wp-content\/uploads\/2022\/04\/logo201911111655359700994.webp","contentUrl":"https:\/\/genrontrucktrailer.com\/wp-content\/uploads\/2022\/04\/logo201911111655359700994.webp","width":160,"height":90,"caption":"Genron International Trade"},"image":{"@id":"https:\/\/genrontrucktrailer.com\/ru\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/genrontrucktrailer.com\/fr\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/genrontrucktrailer.com\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/genrontrucktrailer.com\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/genrontrucktrailer.com\/fr\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}